{"id":435,"date":"2018-07-04T16:03:39","date_gmt":"2018-07-04T14:03:39","guid":{"rendered":"https:\/\/www.rentami.it\/blog\/?p=435"},"modified":"2018-07-04T16:03:39","modified_gmt":"2018-07-04T14:03:39","slug":"assicurazione-rca-slittano-gli-sconti-per-assicurazione-autovetture","status":"publish","type":"post","link":"https:\/\/www.rentami.it\/blog\/assicurazione-rca-slittano-gli-sconti-per-assicurazione-autovetture\/","title":{"rendered":"Assicurazione RCA: Slittano gli sconti"},"content":{"rendered":"<p>Da un lato abbiamo la buona notizia dell\u2019Ivass: sono infatti stati resi noti i dati sull\u2019andamento dell&#8217;<strong>assicurazione rca auto<\/strong>\u00a0con il risultato che dal 2013 al 2017 abbiamo avuto una diminuzione pari a 100 euro sul pagamento; il costo medio della polizza RC Auto, infatti, si aggirerebbe in Italia intorno ai 340 euro.<br \/>\nDall\u2019altro lato, invece, abbiamo il dati contrastanti e non certo rassicuranti: secondo l\u2019ONF infatti, ossia l\u2019<strong>Osservatorio Nazionale Federconsumatori<\/strong>, in seguito ad alcuni monitoraggi che svolge nelle principali citt\u00e0 italiane, \u00e8 emerso un aumento dei costi pari al 27% in pi\u00f9, ossia 144,35 euro annui che pesa sempre pi\u00f9 ai consumatori per la <strong>polizza auto<\/strong>.<br \/>\nLa\u00a0<strong>polizza rca<\/strong> sta quindi mostrando un andamento di dati piuttosto insolito e soprattutto connotato da vari contrasti tra le fonti.<\/p>\n<p style=\"text-align: center;\"><strong>Costi Assicurazione: Per l\u2019Ivass si migliora, per l\u2019ONF andremo sempre peggio.<\/strong><\/p>\n<h2>Assicurazioni auto: l\u2019Italia ha le assicurazioni\u00a0RCA\u00a0pi\u00f9 alte d\u2019Europa.<\/h2>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-438\" src=\"https:\/\/www.rentami.it\/blog\/wp-content\/uploads\/2018\/07\/Pe9ZrJWF_400x400.jpg\" alt=\"\" width=\"245\" height=\"245\" srcset=\"https:\/\/www.rentami.it\/blog\/wp-content\/uploads\/2018\/07\/Pe9ZrJWF_400x400.jpg 245w, https:\/\/www.rentami.it\/blog\/wp-content\/uploads\/2018\/07\/Pe9ZrJWF_400x400-150x150.jpg 150w\" sizes=\"(max-width: 245px) 100vw, 245px\" \/>Secondo quanto riporta sempre l\u2019Osservatorio Nazionale Federconsumatori, infatti, l\u2019Italia ha le <strong>polizze responsabilit\u00e0 civile auto<\/strong> pi\u00f9 alte in tutta Europa ed \u00e8 ben lontana, a livello di dati concreti, dalla media dei nostri vicini.<br \/>\nL\u2019esempio riportato \u00e8 il seguente, giusto per renderci conto: un uomo sui 50 in prima classe con un\u2019auto di cilindrata 1200, pagherebbe una media di ben 668 euro di <strong>assicurazione macchina.<\/strong><\/p>\n<p>Niente a che vedere quindi con gli altri paesi europei, ma bisogna dire che c\u2019\u00e8 chi sta peggio: gli abitanti del Sud Italia.<\/p>\n<p>Per gli abitanti del Sud, infatti, il prezzo dell\u2019<strong>assicurazioni rca<\/strong> e di gran lunga pi\u00f9 elevato rispetto a quello che pagano i consumatori del Nord, ed il divario non pu\u00f2 essere annullato o modificato di tanto nemmeno installando la scatola nera.<\/p>\n<p>Tuttavia il presidente dell\u2019Ivass non la pensa cos\u00ec: a quanto dice, infatti, il prezzo dell&#8217;<strong>assicurazione auto<\/strong> \u00e8 sceso e questo grazie proprio all\u2019istallazione della scatola nera, rendendo l\u2019Italia, tra le altre cose, leader a livello mondiale nella diffusione della <strong>motor connected insurance.<\/strong><\/p>\n<h2>Coperture RCA: gli sconti della scatola nera<\/h2>\n<p>Come abbiamo precedentemente detto, la scatola nera, anche secondo Ivass, dovrebbe far risparmiare parecchio a differenti consumatori sull&#8217;<strong>assicurazione rc auto<\/strong><br \/>\nErano previsti, per questo 9 luglio, degli sconti sulla <strong>copertura rca<\/strong>, proprio per chi decideva di installare questo dispositivo; Salvatore Rossi per\u00f2, presidente dell\u2019Ivass, durante un\u2019intervista al Sole 24 Ore, ha fatto intendere chele cose non andranno come previsto.<br \/>\nIl 9 luglio di quest\u2019anno, infatti, sar\u00e0 pi\u00f9 che altro la data in cui entrer\u00e0 in vigore il regolamento dell\u2019Ivass che fissa i criteri per calcolare gli sconti sulla scatola nera; purtroppo per\u00f2, mancando i decreti ministeriali e la definizione degli <strong>alclock,<\/strong> ossia i dispositivi che dovrebbero bloccare il motore se il guidatore ha bevuto, gli sconti sull&#8217;<strong>assicurazione auto<\/strong>, non potranno partire proprio dal 9 Luglio.<\/p>\n<p>Salvatore Rossi ha cos\u00ec spiegato la situazione: <em><strong>\u201cL\u2019Ivass ha emanato a marzo un nuovo regolamento ed \u00e8 pronto a svolgere il resto degli adempimenti che la legge gli assegna, ma attende per questo i necessari decreti ministeriali attuativi\u201d.<\/strong><\/em><\/p>\n<p>Insomma la situazione potr\u00e0 esser sbloccata solo grazie al ministero, che dovr\u00e0 emanare i decreti necessari a far s\u00ec che gli sconti sulla scatola nera entrino effettivamente in vigore, sgravando il consumatore di parte delle spese sostenute annualmente l&#8217;<strong>assicurazione di responsabilit\u00e0 civile<\/strong> per il veicolo.<img loading=\"lazy\" class=\"alignright size-medium wp-image-439\" src=\"https:\/\/www.rentami.it\/blog\/wp-content\/uploads\/2018\/07\/scatolaneraautomobile147187-300x213.jpg\" alt=\"\" width=\"300\" height=\"213\" \/><br \/>\nIl solito della politica italiana in definitiva: viene fatta una legge ma mancano i mezzi per poterla attuare realmente, considerando inoltre che il regolamento \u00e8 pronto da pi\u00f9 di un mese!<br \/>\nIn questi giorni \u00e8 anche girata la notizia di un\u2019ipotesi, a quanto pare molto probabile, che si stia studiando un sistema di rating unico per ogni guidatore, andando cos\u00ec a sostituire la classe di bonus Mauls, grazie anche a quelli che Salvatore Rossi ha definito i \u201cfattori innovativi\u201d come i sistemi di condivisione auto (<a title=\"differenze car sharing noleggio lungo termine\" href=\"https:\/\/www.rentami.it\/blog\/car-sharing-napoli\/\" target=\"_blank\" rel=\"noopener noreferrer\">car sharing<\/a>).<br \/>\nCi\u00f2 che si pu\u00f2 in definitiva confermare \u00e8 la maggior presenza di scatole nere al Sud Italia, dove purtroppo c\u2019\u00e8 sempre stata una maggior necessit\u00e0 di combattere le frodi pi\u00f9 tosto che al Nord Italia.<\/p>\n<p>Lo slittamento degli sconti, sulle <strong>polizze auto<\/strong>,\u00a0 per quanto non sia una buona notizia, non andr\u00e0 per\u00f2 a peggiorare la situazione: gli sconti, per l&#8217;a<strong>ssicurazione autovetture<\/strong>, che alcuni assicuratori hanno effettuato a beneficio dei consumatori verranno comunque confermati, con il cambiamento che un giorno saranno obbligatori.<\/p>\n<p>L\u2019introduzione della scatola nera ha una grande importanza ed ha apportato parecchi benefici, come lo stop alla costante crescita dei premi\u00a0sulla <strong>polizza assicurativa auto\u00a0<\/strong>in Italia, oppure quello di limitare la disparit\u00e0 di prezzo tra ci\u00f2 che pagano al Nord e ci\u00f2 che \u00e8 invece l\u2019effettiva spesa al Sud Italia (sempre secondo l\u2019Ivass).<\/p>\n<h2>Assicurazione\u00a0RCA pi\u00f9 conveniente<\/h2>\n<p>Chi volesse approfondire il discorso delle <strong>Assicurazione Auto,\u00a0<\/strong>abbiamo pubblicato un ottimo articolo riguardante i Preventivi delle assicurazioni divisi per segmenti e anzianit\u00e0 della vettura, che potete leggere seguendo questo <a title=\"assicurazioni auto low cost\" href=\"https:\/\/www.rentami.it\/blog\/assicurazioni-auto-low-cost\/\" target=\"_blank\" rel=\"noopener noreferrer\">link<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da un lato abbiamo la buona notizia dell\u2019Ivass: sono infatti stati resi noti i dati sull\u2019andamento dell&#8217;assicurazione rca auto\u00a0con il risultato che dal 2013 al 2017 abbiamo avuto una diminuzione pari a 100 euro sul&#8230;<\/p>\n","protected":false},"author":3,"featured_media":437,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/posts\/435"}],"collection":[{"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/comments?post=435"}],"version-history":[{"count":3,"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/posts\/435\/revisions"}],"predecessor-version":[{"id":441,"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/posts\/435\/revisions\/441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/media\/437"}],"wp:attachment":[{"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/media?parent=435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/categories?post=435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rentami.it\/blog\/wp-json\/wp\/v2\/tags?post=435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}